{"id":416,"count":1,"description":"","link":"https:\/\/www.mynameismoney.com\/en\/tag\/akcns-share-analysis\/","name":"akcns hisse analizi","slug":"akcns-hisse-analizi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>akcns hisse analizi ar\u015fivleri | My Name is Money<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mynameismoney.com\/en\/tag\/akcns-hisse-analizi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"akcns hisse analizi ar\u015fivleri | My Name is Money\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mynameismoney.com\/en\/tag\/akcns-hisse-analizi\/\" \/>\n<meta property=\"og:site_name\" content=\"My Name is Money\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mynameismoney4\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mynameismoney.com\/#website\",\"url\":\"https:\/\/www.mynameismoney.com\/\",\"name\":\"MyNameisMoney Blog Sayfas\\u0131 | Bosa | Hisse Senedi | Analiz\",\"description\":\"Herkes i\\u00e7in giri\\u015f ve ileri seviye Teknik Analiz kurslar\\u0131, \\u00e7ok \\u00f6zel teknik analiz indikat\\u00f6rleri ve geli\\u015fmi\\u015f algo-trade yaz\\u0131l\\u0131mlar\\u0131, My Name is Money \\u00d6zel Seri Kitaplar\\u0131na eri\\u015fim i\\u00e7in do\\u011fru adrestesiniz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.mynameismoney.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.mynameismoney.com\/tag\/akcns-hisse-analizi\/#webpage\",\"url\":\"https:\/\/www.mynameismoney.com\/tag\/akcns-hisse-analizi\/\",\"name\":\"akcns hisse analizi ar\\u015fivleri | My Name is Money\",\"isPartOf\":{\"@id\":\"https:\/\/www.mynameismoney.com\/#website\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mynameismoney.com\/tag\/akcns-hisse-analizi\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/www.mynameismoney.com\/en\/wp-json\/wp\/v2\/tags\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mynameismoney.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mynameismoney.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mynameismoney.com\/en\/wp-json\/wp\/v2\/posts?tags=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}